{"id":1,"count":1,"description":"","link":"https:\/\/osservami.com\/index.php\/category\/senza-categoria\/","name":"Senza categoria","slug":"senza-categoria","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/osservami.com\/index.php\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osservami.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/osservami.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/osservami.com\/index.php\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}